{"id":2456,"date":"2025-09-30T13:05:41","date_gmt":"2025-09-30T11:05:41","guid":{"rendered":"https:\/\/arterraceramica.com\/?p=2456"},"modified":"2026-01-12T17:26:19","modified_gmt":"2026-01-12T16:26:19","slug":"rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt","status":"publish","type":"post","link":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/","title":{"rendered":"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt"},"content":{"rendered":"<p data-start=\"11060\" data-end=\"11605\"><strong>Die Stadtr\u00e4tin f\u00fcr Tourismus und Handwerk, Gelen Delgado, hob hervor, dass das Projekt CeramiTUR nach 20 Workshops und 4 gef\u00fchrten Besichtigungen in Talavera mit \u201esehr positiven\u201c Ergebnissen und Eindr\u00fccken abgeschlossen wurde. Rund 300 Menschen aus unterschiedlichsten Bereichen erlebten pers\u00f6nlich \u201edie Kunst, den Ton zwischen den Fingern zu sp\u00fcren und die Schwierigkeit, ein Keramikst\u00fcck zu bemalen\u201c, was zu einer gr\u00f6\u00dferen Wertsch\u00e4tzung \u201eunserer handwerklichen Prozesse, die als Immaterielles Kulturerbe der Menschheit anerkannt sind\u201c, f\u00fchrte.<\/strong><\/p>\n<p data-start=\"11607\" data-end=\"11868\">Sie \u00e4u\u00dferte sich hierzu auf einer Pressekonferenz gemeinsam mit Fernando Portela, Projektkoordinator, Cristina Vilches, Organisatorin inklusiver und sensibilisierender Aktivit\u00e4ten, sowie Mar\u00eda Godoy, Beauftragte f\u00fcr Tourismusf\u00f6rderung und \u00d6ffentlichkeitsarbeit.<\/p>\n<p data-start=\"11870\" data-end=\"12540\">Delgado erinnerte daran, dass CeramiTUR ein Projekt ist, das mit dem Ziel ins Leben gerufen wurde, Keramik als touristische Attraktion zu st\u00e4rken und traditionelles keramisches Know-how in hochwertige, inklusive und attraktive Tourismusangebote f\u00fcr Einheimische und Besucher umzuwandeln. Die Initiative wurde von Talavera gemeinsam mit der Spanischen Vereinigung der Keramikst\u00e4dte geleitet, in Zusammenarbeit mit Gemeinden mit keramischer Tradition (Agost, Alba de Tormes, Bail\u00e9n, La Bisbal d\u2019Empord\u00e0, La Rambla, Manises, Mota del Cuervo und Onda), und durch den Wiederaufbau-, Transformations- und Resilienzplan der Europ\u00e4ischen Union \u2013 Next Generation EU \u2013 finanziert.<\/p>\n<p data-start=\"12542\" data-end=\"12562\"><strong>CERAMITUR-MASSNAHMEN<\/strong><\/p>\n<p data-start=\"12564\" data-end=\"12817\">Die Stadtr\u00e4tin erkl\u00e4rte, dass sich das CeramiTUR-Programm in der Stadt auf zwei Hauptaktionslinien konzentrierte, die das gesamte Projekt umfassten: touristische F\u00f6rderung und \u00d6ffentlichkeitsarbeit sowie Sensibilisierung, Inklusion und Barrierefreiheit.<\/p>\n<p data-start=\"12819\" data-end=\"13199\">Die erste Linie brachte den handwerklichen Herstellungsprozess jungen Menschen mit Risiko sozialer Ausgrenzung n\u00e4her; Frauen und Kindern, die Opfer geschlechtsspezifischer Gewalt sind; Minderj\u00e4hrigen unter Schutzma\u00dfnahmen; Menschen mit geistigen, k\u00f6rperlichen oder sensorischen Behinderungen; Personen mit Mindesteinkommen sowie Gefl\u00fcchteten in Zusammenarbeit mit dem Roten Kreuz.<\/p>\n<p data-start=\"13201\" data-end=\"13747\">Dar\u00fcber hinaus wurden Workshops mit Organisationen wie ALPADIF durchgef\u00fchrt; mit sehbehinderten Teilnehmenden in Zusammenarbeit mit der ONCE; mit Sch\u00fclern mit geistiger Behinderung bei Manos Artesanas; mit Teilnehmenden von APACE mit zerebraler L\u00e4hmung und Behinderungen; ein Ton- und Malkurs in der Abteilung f\u00fcr Suchtverhalten und Psychiatrie; sowie eine Route mit dem Verein \u201eCon Otro Sentido\u201c, die es Menschen mit eingeschr\u00e4nkter Mobilit\u00e4t und unterschiedlichen F\u00e4higkeiten erm\u00f6glichte, das kulturelle Erbe der Stadt barrierefrei zu genie\u00dfen.<\/p>\n<p data-start=\"13749\" data-end=\"14153\">Im zweiten Aktionsbereich \u2014 der touristischen F\u00f6rderung \u2014 nahmen Berufsverb\u00e4nde an Routen sowie T\u00f6pfer- und Malworkshops teil, darunter offizielle Stadtf\u00fchrer aus Toledo, Tourismusfachleute und -unternehmen, Gro\u00dffamilienverb\u00e4nde aus Talavera und Madrid, junge Menschen im Alter von 14 bis 35 Jahren bei einem Malworkshop im Jugendzentrum, Einwohner von Talavera sowie Einzelpersonen mit freier Anmeldung.<\/p>\n<p data-start=\"14155\" data-end=\"14450\">Delgado betonte, dass all diese Ma\u00dfnahmen \u201eeinen starken Impuls f\u00fcr die handwerklichen Werkst\u00e4tten darstellten und das Interesse sowie die Anerkennung des Sektors erh\u00f6hten, ebenso wie die Wertsch\u00e4tzung f\u00fcr den Einsatz und die M\u00fche, die Kunsthandwerker in jedes keramische Werkst\u00fcck investieren\u201c.<\/p>\n<p data-start=\"14452\" data-end=\"14685\">In diesem Jahr wurde zudem ein Anstieg der Einschreibungen in die Ausbildungsprogramme f\u00fcr K\u00fcnstlerische Keramik (h\u00f6here Berufsausbildung) und Keramikdekoration (mittlere Berufsausbildung) an der Kunstschule von Talavera verzeichnet.<\/p>\n<p data-start=\"14687\" data-end=\"14856\">\u201eWir k\u00f6nnen daher feiern, dass unsere Keramik \u2014 unser Stolz als Einwohner von Talavera und unser Erkennungszeichen \u2014 nach und nach den Platz einnimmt, den sie verdient.\u201c<\/p>\n<p data-start=\"14858\" data-end=\"15233\">Sie nutzte au\u00dferdem die Gelegenheit, allen zu danken, die die Durchf\u00fchrung dieser Aktivit\u00e4ten erm\u00f6glicht haben, insbesondere den Kunsthandwerkern und Fachleuten an Drehscheibe und Pinsel, die \u201eihre T\u00fcren ge\u00f6ffnet haben, um Workshops anzubieten, die allen Teilnehmenden in Erinnerung bleiben werden, und die mit gro\u00dfer Sorgfalt und Hingabe ihre t\u00e4gliche Arbeit gezeigt haben\u201c.<\/p>\n<p data-start=\"15235\" data-end=\"15668\">Das Projekt umfasste zudem \u00fcbergreifende Ma\u00dfnahmen mit einem Multimedia-Team, das Inhalte und Ressourcen zu Gesch\u00e4ften aufnahm, die Keramik an ihren Fassaden oder in ihrem Geschirr verwenden, sowie zum kulturellen Erbe \u2014 Wandbilder, Basilika, Br\u00fccken mit keramischen Fliesenarbeiten \u2014 und zwei Masterclasses, eine zu Malerei und Dekoration und eine zur T\u00f6pferei, um den gesamten Herstellungsprozess eines Keramikst\u00fccks zu vermitteln.<\/p>\n<p data-start=\"15670\" data-end=\"15927\">All dieses Material wird auf eine mehrsprachige Webplattform hochgeladen, die das gesamte keramisch-touristische Angebot b\u00fcndelt und die Reiseplanung, die Einsicht in Aktivit\u00e4ten, Reservierungen sowie den Zugang zu inklusiven Multimedia-Inhalten erm\u00f6glicht.<\/p>\n<p data-start=\"15929\" data-end=\"15951\"><strong>NATIONALE KERAMIKROUTE<\/strong><\/p>\n<p data-start=\"15953\" data-end=\"16288\">Abschlie\u00dfend wurde die Schaffung einer Nationalen Keramikroute angek\u00fcndigt, ein kulturelles Tourismusprojekt, koordiniert von der Spanischen Vereinigung der Keramikst\u00e4dte, das darauf abzielt, das keramische Erbe Spaniens durch immersive Erlebnisse in angeschlossenen St\u00e4dten zu f\u00f6rdern und sich mit der Europ\u00e4ischen Route zu vernetzen.<\/p>\n<p data-start=\"16290\" data-end=\"16545\">Die Route wird Museumsbesuche, traditionelle Brenn\u00f6fen, Interpretationszentren, partizipative Workshops mit lokalen Keramikern, thematische Routen, Bildungsaktivit\u00e4ten, Familienerlebnisse, Gastronomie sowie mit der Keramik verbundene Unterk\u00fcnfte umfassen.<\/p>\n<p data-start=\"16547\" data-end=\"16606\">F\u00fcr 2026 ist zudem ein Nationaler T\u00f6pferwettbewerb geplant.<\/p>\n<p data-start=\"16608\" data-end=\"16798\" data-is-last-node=\"\" data-is-only-node=\"\">Fernando Portela k\u00fcndigte an, dass nach Abschluss von CeramiTUR eine neue Marke als Identit\u00e4t der Nationalen Keramikroute vorgestellt wird: ARTERRA \u2013 \u201eOrte, an denen die Erde lebendig wird\u201c.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Stadtr\u00e4tin f\u00fcr Tourismus und Handwerk, Gelen Delgado, hob hervor,  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":2455,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[120],"tags":[],"class_list":["post-2456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt - ARTERRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt - ARTERRA\" \/>\n<meta property=\"og:description\" content=\"Die Stadtr\u00e4tin f\u00fcr Tourismus und Handwerk, Gelen Delgado, hob hervor, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/\" \/>\n<meta property=\"og:site_name\" content=\"ARTERRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arterra_ceramica\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T11:05:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T16:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/talavera-arterra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2016\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lyspum Studio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lyspum Studio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/\"},\"author\":{\"name\":\"Lyspum Studio\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/person\\\/18221130fe4eea18c23834795a745cf9\"},\"headline\":\"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt\",\"datePublished\":\"2025-09-30T11:05:41+00:00\",\"dateModified\":\"2026-01-12T16:26:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/\"},\"wordCount\":801,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/talavera-arterra.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/\",\"name\":\"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt - ARTERRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/talavera-arterra.jpg\",\"datePublished\":\"2025-09-30T11:05:41+00:00\",\"dateModified\":\"2026-01-12T16:26:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/talavera-arterra.jpg\",\"contentUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/talavera-arterra.jpg\",\"width\":2016,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#website\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/\",\"name\":\"ARTERRA\",\"description\":\"Lugares donde la tierra cobra vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#organization\"},\"alternateName\":\"Lugares donde la tierra cobra vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arterraceramica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#organization\",\"name\":\"ARTERRA\",\"alternateName\":\"Lugares donde la tierra cobra vida\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-arterra-header-web.png\",\"contentUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-arterra-header-web.png\",\"width\":1485,\"height\":365,\"caption\":\"ARTERRA\"},\"image\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arterra_ceramica\\\/\",\"https:\\\/\\\/www.instagram.com\\\/arterra_ceramica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/person\\\/18221130fe4eea18c23834795a745cf9\",\"name\":\"Lyspum Studio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g\",\"caption\":\"Lyspum Studio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt - ARTERRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/","og_locale":"de_DE","og_type":"article","og_title":"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt - ARTERRA","og_description":"Die Stadtr\u00e4tin f\u00fcr Tourismus und Handwerk, Gelen Delgado, hob hervor, [...]","og_url":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/","og_site_name":"ARTERRA","article_publisher":"https:\/\/www.facebook.com\/arterra_ceramica\/","article_published_time":"2025-09-30T11:05:41+00:00","article_modified_time":"2026-01-12T16:26:19+00:00","og_image":[{"width":2016,"height":1512,"url":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/talavera-arterra.jpg","type":"image\/jpeg"}],"author":"Lyspum Studio","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lyspum Studio","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#article","isPartOf":{"@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/"},"author":{"name":"Lyspum Studio","@id":"https:\/\/arterraceramica.com\/#\/schema\/person\/18221130fe4eea18c23834795a745cf9"},"headline":"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt","datePublished":"2025-09-30T11:05:41+00:00","dateModified":"2026-01-12T16:26:19+00:00","mainEntityOfPage":{"@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/"},"wordCount":801,"commentCount":0,"publisher":{"@id":"https:\/\/arterraceramica.com\/#organization"},"image":{"@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#primaryimage"},"thumbnailUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/talavera-arterra.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/","url":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/","name":"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt - ARTERRA","isPartOf":{"@id":"https:\/\/arterraceramica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#primaryimage"},"image":{"@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#primaryimage"},"thumbnailUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/talavera-arterra.jpg","datePublished":"2025-09-30T11:05:41+00:00","dateModified":"2026-01-12T16:26:19+00:00","breadcrumb":{"@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#primaryimage","url":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/talavera-arterra.jpg","contentUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/talavera-arterra.jpg","width":2016,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/arterraceramica.com\/de\/rund-300-menschen-haben-die-handwerklichen-herstellungsprozesse-talaveras-durch-ceramitur-erlebt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arterraceramica.com\/de\/"},{"@type":"ListItem","position":2,"name":"Rund 300 Menschen haben die handwerklichen Herstellungsprozesse Talaveras durch CeramiTUR erlebt"}]},{"@type":"WebSite","@id":"https:\/\/arterraceramica.com\/#website","url":"https:\/\/arterraceramica.com\/","name":"ARTERRA","description":"Lugares donde la tierra cobra vida","publisher":{"@id":"https:\/\/arterraceramica.com\/#organization"},"alternateName":"Lugares donde la tierra cobra vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arterraceramica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/arterraceramica.com\/#organization","name":"ARTERRA","alternateName":"Lugares donde la tierra cobra vida","url":"https:\/\/arterraceramica.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arterraceramica.com\/#\/schema\/logo\/image\/","url":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/logo-arterra-header-web.png","contentUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/logo-arterra-header-web.png","width":1485,"height":365,"caption":"ARTERRA"},"image":{"@id":"https:\/\/arterraceramica.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arterra_ceramica\/","https:\/\/www.instagram.com\/arterra_ceramica"]},{"@type":"Person","@id":"https:\/\/arterraceramica.com\/#\/schema\/person\/18221130fe4eea18c23834795a745cf9","name":"Lyspum Studio","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g","caption":"Lyspum Studio"}}]}},"_links":{"self":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts\/2456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/comments?post=2456"}],"version-history":[{"count":1,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts\/2456\/revisions"}],"predecessor-version":[{"id":2457,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts\/2456\/revisions\/2457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/media\/2455"}],"wp:attachment":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/media?parent=2456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/categories?post=2456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/tags?post=2456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}