{"id":3541,"date":"2026-04-07T15:21:30","date_gmt":"2026-04-07T13:21:30","guid":{"rendered":"https:\/\/arterraceramica.com\/?p=3541"},"modified":"2026-04-07T15:24:31","modified_gmt":"2026-04-07T13:24:31","slug":"hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen","status":"publish","type":"post","link":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/","title":{"rendered":"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen"},"content":{"rendered":"<div class=\"flex flex-col text-sm pb-25\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:6c8b5780-808c-4f27-ae24-49b8b20ee211-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"e4259a4d-a571-403b-a126-6d74a9de32c8\" data-message-model-slug=\"gpt-5-4-thinking\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word dark markdown-new-styling\">\n<p data-start=\"7335\" data-end=\"7823\">Die Spanische Vereinigung der Keramikst\u00e4dte (AeCC) organisiert vom 7. bis 12. April eine neue Ausgabe von Hola Cer\u00e1mica 2026, einer Initiative, die darauf ausgerichtet ist, Keramik durch Workshops, Tage der offenen T\u00fcr, F\u00fchrungen, Ausstellungen, Vorf\u00fchrungen und Vermittlungsaktivit\u00e4ten einem breiten Publikum zug\u00e4nglich zu machen. Die Veranstaltung ist Teil des Kalenders der Europ\u00e4ischen Tage des Kunsthandwerks, die im selben Zeitraum in verschiedenen europ\u00e4ischen L\u00e4ndern stattfinden.<\/p>\n<p data-start=\"7825\" data-end=\"8350\">Diese Ausgabe wird 64 Pr\u00e4senzveranstaltungen in 18 Gemeinden umfassen und best\u00e4tigt damit die territoriale Reichweite eines Programms, das erneut sowohl die traditionelle Keramik als auch ihre zeitgen\u00f6ssischen Ausdrucksformen in den Mittelpunkt stellt. Das Programm vereint Initiativen in Alba de Tormes, Argentona, Arroyo de la Luz, Bail\u00e9n, Barcelona, Bollullos de la Mitaci\u00f3n, Breda, Esplugues de Llobregat, Gelves, La Bisbal d\u2019Empord\u00e0, La Galera, La Rambla, Manises, Muel, Onda, Portillo, Sevilla und Talavera de la Reina.<\/p>\n<p data-start=\"8352\" data-end=\"8943\">Hola Cer\u00e1mica entstand als eine Initiative zur Belebung und \u00d6ffnung von Werkst\u00e4tten, Museen und anderen keramischen Einrichtungen, um ihre Arbeit sichtbar zu machen und die Verbindung zwischen der Bev\u00f6lkerung und einem Handwerk zu st\u00e4rken, das Teil des kulturellen, wirtschaftlichen und sozialen Erbes zahlreicher spanischer Gemeinden ist. Die AeCC selbst, die St\u00e4dte mit historischer Verbindung zur Keramik vereint, setzt sich genau daf\u00fcr ein, dieses Erbe zu sch\u00fctzen, die Entwicklung des Kunsthandwerkssektors zu f\u00f6rdern und den mit dieser Tradition verbundenen Kulturtourismus zu st\u00e4rken.<\/p>\n<p data-start=\"8945\" data-end=\"9373\">Das Programm 2026 zeigt erneut diese Vielfalt. Es gibt Angebote, die sich auf traditionelle T\u00f6pferei konzentrieren, wie Tage der offenen T\u00fcr in Werkst\u00e4tten und Museen; Einf\u00fchrungs- und Mitmachaktivit\u00e4ten mit Workshops f\u00fcr Kinder und Erwachsene; Routen, die mit dem lokalen keramischen Erbe verbunden sind; sowie Inhalte, die Keramik mit aktuellen Debatten \u00fcber Ausbildung, Kreativit\u00e4t, Innovation oder Herkunftsschutz verbinden.<\/p>\n<p data-start=\"9375\" data-end=\"9628\">In Gelves finden beispielsweise Veranstaltungen zu gesch\u00fctzten geografischen Angaben im Bereich der handwerklichen Keramik statt (9. April, 10:00 Uhr), ein Arbeitsfeld, mit dem sich die AeCC bereits in ihren j\u00fcngsten technischen Treffen besch\u00e4ftigt hat.<\/p>\n<p data-start=\"9630\" data-end=\"10275\">Die zeitliche \u00dcberschneidung mit den Europ\u00e4ischen Tagen des Kunsthandwerks ordnet Hola Cer\u00e1mica zudem in einen breiteren Rahmen zur F\u00f6rderung des Kunsthandwerks ein. In Spanien werden die Europ\u00e4ischen Tage des Kunsthandwerks von Fundesarte, dem Bereich zur F\u00f6rderung des Kunsthandwerks der Escuela de Organizaci\u00f3n Industrial (EOI), in Zusammenarbeit mit der spanischen Organisation der Kunsthandwerker, Oficio y Arte, sowie der European Crafts Alliance getragen. Ziel ist es, der \u00d6ffentlichkeit die Prozesse, das Wissen und die Werte der handwerklichen Berufe durch offene, kostenlose und im ganzen Land stattfindende Aktivit\u00e4ten n\u00e4herzubringen.<\/p>\n<p data-start=\"10277\" data-end=\"10593\">Auch die internationale Dimension pr\u00e4gt diese Ausgabe. Die AeCC unterh\u00e4lt Kooperationsbeziehungen zu anderen europ\u00e4ischen Vereinigungen von Keramikst\u00e4dten, und in Italien wird die AiCC 2026 erneut eine neue Ausgabe von <em data-start=\"10496\" data-end=\"10517\">Buongiorno Ceramica<\/em> veranstalten, ihre gro\u00dfe j\u00e4hrliche Veranstaltung zur F\u00f6rderung der Keramik.<\/p>\n<p data-start=\"10595\" data-end=\"10910\">Mit dieser neuen Ausgabe st\u00e4rkt Hola Cer\u00e1mica ihre Rolle als eine der wichtigsten Initiativen zur Vermittlung und F\u00f6rderung der Keramik in Spanien, indem sie Kulturerbe, Live-Vorf\u00fchrungen, B\u00fcrgerbeteiligung und Wissen \u00fcber das Handwerk in einer Woche verbindet, in der die Keramik erneut im Mittelpunkt stehen wird.<\/p>\n<p data-start=\"10912\" data-end=\"11050\" data-is-last-node=\"\" data-is-only-node=\"\">Si quieres, te lo puedo dejar tambi\u00e9n en un formato m\u00e1s <strong data-start=\"10968\" data-end=\"10992\">natural\/publicitario<\/strong> o m\u00e1s <strong data-start=\"10999\" data-end=\"11016\">institucional<\/strong>, seg\u00fan d\u00f3nde lo vayas a publicar.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Spanische Vereinigung der Keramikst\u00e4dte (AeCC) organisiert vom 7. bis  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":3540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-3541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reiseziele"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen - ARTERRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen - ARTERRA\" \/>\n<meta property=\"og:description\" content=\"Die Spanische Vereinigung der Keramikst\u00e4dte (AeCC) organisiert vom 7. bis [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/\" \/>\n<meta property=\"og:site_name\" content=\"ARTERRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arterra_ceramica\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T13:21:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T13:24:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arterraceramica.com\/wp-content\/uploads\/2026\/04\/cartel-hola-ceramica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lyspum Studio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lyspum Studio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/\"},\"author\":{\"name\":\"Lyspum Studio\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/person\\\/18221130fe4eea18c23834795a745cf9\"},\"headline\":\"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen\",\"datePublished\":\"2026-04-07T13:21:30+00:00\",\"dateModified\":\"2026-04-07T13:24:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cartel-hola-ceramica.jpg\",\"articleSection\":[\"Reiseziele\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/\",\"name\":\"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen - ARTERRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cartel-hola-ceramica.jpg\",\"datePublished\":\"2026-04-07T13:21:30+00:00\",\"dateModified\":\"2026-04-07T13:24:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cartel-hola-ceramica.jpg\",\"contentUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/cartel-hola-ceramica.jpg\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/arterraceramica.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#website\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/\",\"name\":\"ARTERRA\",\"description\":\"Lugares donde la tierra cobra vida\",\"publisher\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#organization\"},\"alternateName\":\"Lugares donde la tierra cobra vida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arterraceramica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#organization\",\"name\":\"ARTERRA\",\"alternateName\":\"Lugares donde la tierra cobra vida\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-arterra-header-web.png\",\"contentUrl\":\"https:\\\/\\\/arterraceramica.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-arterra-header-web.png\",\"width\":1485,\"height\":365,\"caption\":\"ARTERRA\"},\"image\":{\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/arterra_ceramica\\\/\",\"https:\\\/\\\/www.instagram.com\\\/arterra_ceramica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arterraceramica.com\\\/#\\\/schema\\\/person\\\/18221130fe4eea18c23834795a745cf9\",\"name\":\"Lyspum Studio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g\",\"caption\":\"Lyspum Studio\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen - ARTERRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/","og_locale":"de_DE","og_type":"article","og_title":"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen - ARTERRA","og_description":"Die Spanische Vereinigung der Keramikst\u00e4dte (AeCC) organisiert vom 7. bis [...]","og_url":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/","og_site_name":"ARTERRA","article_publisher":"https:\/\/www.facebook.com\/arterra_ceramica\/","article_published_time":"2026-04-07T13:21:30+00:00","article_modified_time":"2026-04-07T13:24:31+00:00","og_image":[{"width":1414,"height":2000,"url":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2026\/04\/cartel-hola-ceramica.jpg","type":"image\/jpeg"}],"author":"Lyspum Studio","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lyspum Studio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#article","isPartOf":{"@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/"},"author":{"name":"Lyspum Studio","@id":"https:\/\/arterraceramica.com\/#\/schema\/person\/18221130fe4eea18c23834795a745cf9"},"headline":"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen","datePublished":"2026-04-07T13:21:30+00:00","dateModified":"2026-04-07T13:24:31+00:00","mainEntityOfPage":{"@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/arterraceramica.com\/#organization"},"image":{"@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#primaryimage"},"thumbnailUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2026\/04\/cartel-hola-ceramica.jpg","articleSection":["Reiseziele"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/","url":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/","name":"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen - ARTERRA","isPartOf":{"@id":"https:\/\/arterraceramica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#primaryimage"},"image":{"@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#primaryimage"},"thumbnailUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2026\/04\/cartel-hola-ceramica.jpg","datePublished":"2026-04-07T13:21:30+00:00","dateModified":"2026-04-07T13:24:31+00:00","breadcrumb":{"@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#primaryimage","url":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2026\/04\/cartel-hola-ceramica.jpg","contentUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2026\/04\/cartel-hola-ceramica.jpg","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/arterraceramica.com\/de\/hola-ceramica-2026-wird-mehr-als-60-praesenzveranstaltungen-in-rund-zwanzig-gemeinden-zusammenbringen-um-keramik-einem-breiten-publikum-naeherzubringen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arterraceramica.com\/de\/"},{"@type":"ListItem","position":2,"name":"Hola Cer\u00e1mica 2026 wird mehr als 60 Pr\u00e4senzveranstaltungen in rund zwanzig Gemeinden zusammenbringen, um Keramik einem breiten Publikum n\u00e4herzubringen"}]},{"@type":"WebSite","@id":"https:\/\/arterraceramica.com\/#website","url":"https:\/\/arterraceramica.com\/","name":"ARTERRA","description":"Lugares donde la tierra cobra vida","publisher":{"@id":"https:\/\/arterraceramica.com\/#organization"},"alternateName":"Lugares donde la tierra cobra vida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arterraceramica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/arterraceramica.com\/#organization","name":"ARTERRA","alternateName":"Lugares donde la tierra cobra vida","url":"https:\/\/arterraceramica.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/arterraceramica.com\/#\/schema\/logo\/image\/","url":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/logo-arterra-header-web.png","contentUrl":"https:\/\/arterraceramica.com\/wp-content\/uploads\/2025\/09\/logo-arterra-header-web.png","width":1485,"height":365,"caption":"ARTERRA"},"image":{"@id":"https:\/\/arterraceramica.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arterra_ceramica\/","https:\/\/www.instagram.com\/arterra_ceramica"]},{"@type":"Person","@id":"https:\/\/arterraceramica.com\/#\/schema\/person\/18221130fe4eea18c23834795a745cf9","name":"Lyspum Studio","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6217eb5fe2f454a11a1680b83f895ebb850767cc402039786aad7b000334155?s=96&d=mm&r=g","caption":"Lyspum Studio"}}]}},"_links":{"self":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts\/3541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/comments?post=3541"}],"version-history":[{"count":1,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts\/3541\/revisions"}],"predecessor-version":[{"id":3542,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/posts\/3541\/revisions\/3542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/media\/3540"}],"wp:attachment":[{"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/media?parent=3541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/categories?post=3541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arterraceramica.com\/de\/wp-json\/wp\/v2\/tags?post=3541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}